{"id":5582,"date":"2024-09-09T06:21:28","date_gmt":"2024-09-09T06:21:28","guid":{"rendered":"https:\/\/astonisa.com\/?post_type=dt_portfolio&#038;p=5582"},"modified":"2026-02-06T03:00:47","modified_gmt":"2026-02-06T03:00:47","slug":"tavolo-trasformabile-da-rotondo-a-ovale-con-piani-in-ceramica-dt8987","status":"publish","type":"dt_portfolio","link":"https:\/\/astonisa.com\/it\/product\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\/","title":{"rendered":"Tabella DT8987"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner vc_custom_1603589776265\"><div class=\"wpb_wrapper\"><style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div {\n  width: 18px;\n  height: 18px;\n  border-radius: 100px;\n}\n.dt-arrow-border-on.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div:not(:hover):before {\n  border-width: 0px;\n}\n.dt-arrow-hover-border-on.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div:hover:after {\n  border-width: 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div.owl-prev {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  left: 0px;\n}\n@media all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div.owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div.owl-prev i {\n  padding: 0px 0px 0px 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div.owl-next {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  right: 0px;\n}\n@media all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div.owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div.owl-next i {\n  padding: 0px 0px 0px 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav i {\n  font-size: 8px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div:not(:hover) i,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div:not(:hover) i:before {\n  color: #ffffff;\n  background: none;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div:hover i,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.owl-carousel .owl-nav div:hover i:before {\n  color: rgba(255,255,255,0.75);\n  background: none;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e .owl-dots {\n  top: calc(100% + 20px);\n  left: 50%;\n  transform: translateX(calc(-50% + 0px));\n}\n@media all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e .owl-dots {\n    transform: translateX(-50%);\n    margin-left: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e .owl-dot {\n  width: 10px;\n  height: 10px;\n  margin: 0 8px;\n}\n@media screen and (max-width: 778px) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.hide-arrows .owl-nav a {\n    display: none;\n  }\n}\n@media screen and (max-width: 778px) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.reposition-arrows .owl-nav div.owl-prev {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    left: 5px;\n  }\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.reposition-arrows .owl-nav div.owl-next {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    right: 5px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.reposition-arrows .owl-nav div.owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.reposition-arrows .owl-nav div.owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e figure,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e .rollover,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e img,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e .gallery-rollover {\n  border-radius: 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.enable-bg-rollover .gallery-rollover {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.enable-img-shadow .owl-stage-outer {\n  padding: 14px 0;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.enable-bg-rollover.hover-scale figure .rollover:after {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.gallery-shortcode .gallery-zoom-ico {\n  width: 44px;\n  height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  margin: -22px 0 0 -22px;\n  border-width: 0px;\n}\n.dt-icon-bg-on.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.gallery-shortcode .gallery-zoom-ico {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.gallery-shortcode .gallery-zoom-ico:before,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e.gallery-shortcode .gallery-zoom-ico span {\n  font-size: 32px;\n  line-height: 44px;\n  color: #ffffff;\n  background: none;\n}<\/style><div class=\"owl-carousel gallery-carousel-shortcode gallery-shortcode  dt-gallery-container dt-owl-carousel-call gallery-carousel-shortcode-id-a734da206a088e026448b910a2137a3e quick-scale-img meta-info-off dt-arrow-border-on dt-arrow-hover-border-on bullets-small-dot-stroke reposition-arrows dt-icon-bg-off arrows-bg-on disable-arrows-hover-bg arrows-hover-bg-on  vc_custom_1725862569227 hover-fade\" data-scroll-mode=\"1\" data-col-num=\"1\" data-wide-col-num=\"1\" data-laptop-col=\"1\" data-h-tablet-columns-num=\"1\" data-v-tablet-columns-num=\"1\" data-phone-columns-num=\"1\" data-col-gap=\"10\" data-stage-padding=\"0\" data-speed=\"600\" data-autoplay=\"true\" data-autoplay_speed=\"6000\" data-arrows=\"true\" data-bullet=\"false\" data-next-icon=\"icon-ar-017-r\" data-prev-icon=\"icon-ar-017-l\" data-img-shadow-size=\"12px\" data-img-shadow-spread=\"3px\"><div data-post-id=\"5585\" data-date=\"2024-09-09T06:12:51+00:00\" data-name=\"DT8987 round extendable table with ceramic tops\"><figure class=\"post\"><a href=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-2.webp\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"800\" data-large_image_height=\"600\" data-dt-img-description=\"\" title=\"DT8987 tavolo rotondo allungabile con piani in ceramica\"><img fetchpriority=\"high\" decoding=\"async\" class=\"preload-me owl-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20800%20600&#39;%2F%3E\" data-src=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-2.webp\" data-srcset=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-2.webp 800w\" loading=\"eager\" style=\"--ratio: 800 \/ 600\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"DT8987 tavolo rotondo allungabile con piani in ceramica\" width=\"800\" height=\"600\"  \/><span class=\"gallery-rollover\"><span class=\"gallery-zoom-ico icomoon-the7-font-the7-zoom-06\"><span><\/span><\/span><\/span><\/a><\/figure><\/div><div data-post-id=\"5586\" data-date=\"2024-09-09T06:12:53+00:00\" data-name=\"Extendable table DT8987 with extension panel in the middle\"><figure class=\"post\"><a href=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-3.webp\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"800\" data-large_image_height=\"600\" data-dt-img-description=\"\" title=\"Tavolo allungabile DT8987 con pannello di prolunga centrale\"><img decoding=\"async\" class=\"preload-me owl-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20800%20600&#39;%2F%3E\" data-src=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-3.webp\" data-srcset=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-3.webp 800w\" loading=\"eager\" style=\"--ratio: 800 \/ 600\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"Tavolo allungabile DT8987 con pannello di prolunga centrale\" width=\"800\" height=\"600\"  \/><span class=\"gallery-rollover\"><span class=\"gallery-zoom-ico icomoon-the7-font-the7-zoom-06\"><span><\/span><\/span><\/span><\/a><\/figure><\/div><div data-post-id=\"5587\" data-date=\"2024-09-09T06:12:55+00:00\" data-name=\"DT8987 extended table with ceramic top\"><figure class=\"post\"><a href=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-4.webp\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"800\" data-large_image_height=\"600\" data-dt-img-description=\"\" title=\"DT8987 tavolo allungato con piano in ceramica\"><img decoding=\"async\" class=\"preload-me owl-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20800%20600&#39;%2F%3E\" data-src=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-4.webp\" data-srcset=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-4.webp 800w\" loading=\"eager\" style=\"--ratio: 800 \/ 600\" sizes=\"(max-width: 800px) 100vw, 800px\" alt=\"DT8987 tavolo allungato con piano in ceramica\" width=\"800\" height=\"600\"  \/><span class=\"gallery-rollover\"><span class=\"gallery-zoom-ico icomoon-the7-font-the7-zoom-06\"><span><\/span><\/span><\/span><\/a><\/figure><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1725862998878\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Elevate la vostra linea di mobili da pranzo con il DT8987, un sofisticato tavolo da pranzo espandibile progettato per soddisfare le esigenze in evoluzione dei mercati globali.<\/p>\n<p>I distributori di mobili, gli importatori e i marchi che cercano soluzioni di tavoli da pranzo di alta gamma di forma rotonda o ovale, esteticamente piacevoli e funzionali, troveranno grandi idee in questo tavolo rotondo DT8987.<\/p>\n<p><strong>Caratteristiche principali:<\/strong><\/p>\n<ol>\n<li>Design espandibile:<\/li>\n<\/ol>\n<p>- Il TAVOLO rotondo si trasforma in OBLONG per accogliere pi\u00f9 ospiti.<\/p>\n<p>- Pannello di estensione nascosto per una trasformazione senza soluzione di continuit\u00e0<\/p>\n<ol start=\"2\">\n<li>Piano d'appoggio in ceramica premium:<\/li>\n<\/ol>\n<p>- Un sorprendente motivo grigio e bianco ad effetto marmo<\/p>\n<p>- Superficie durevole e resistente ai graffi<\/p>\n<p>- Facile manutenzione per uso commerciale e residenziale<\/p>\n<ol start=\"3\">\n<li>Costruzione robusta:<\/li>\n<\/ol>\n<p>- L'elegante base in metallo nero garantisce la stabilit\u00e0<\/p>\n<p>- Progettato per durare a lungo e per l'uso quotidiano<\/p>\n<ol start=\"4\">\n<li>Posti a sedere complementari (opzionali):<\/li>\n<\/ol>\n<p>- Sedie in peluche, di colore rosa blush con struttura in metallo nero<\/p>\n<p>- Schienale curvo e sedili imbottiti per un comfort ottimale<\/p>\n<p>- Sedie disponibili separatamente o come set<\/p>\n<ol start=\"5\">\n<li>Adatto a sale da pranzo o soggiorni residenziali di alto livello<\/li>\n<\/ol>\n<p><strong>Opzioni di personalizzazione<\/strong>:<\/p>\n<p>- Disponibile in pi\u00f9 dimensioni per soddisfare le diverse esigenze del mercato<\/p>\n<p>- Modelli di ceramica e finiture di base personalizzati (MOQ 20 pezzi)<\/p>\n<p>- Opzioni di sedie abbinate o a contrasto<\/p>\n<p><strong>Perch\u00e9 scegliere DT8987:<\/strong><\/p>\n<p>- L'artigianato di alta qualit\u00e0 incontra un design innovativo<\/p>\n<p>- Combina l'estetica di lusso con la funzionalit\u00e0 pratica<\/p>\n<p>Collaborate con noi per portare questa soluzione gastronomica di alto livello sul vostro mercato<\/p>\n<p>Richiedete oggi stesso un preventivo, un catalogo o un campione.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"ultimate-video-93636a04bb67312fe\" class=\"ult-video  ult-adjust-bottom-margin ultimate-video-93636a04bb67312fe ultv-9127\"><div class=\"ultv-video ultv-aspect-ratio-16_9 ultv-subscribe-responsive-none\" data-videotype=\"uv_iframe\">\n\t\t\t\t\t\t<div class=\"ultv-video__outer-wrap\" data-autoplay=\"0\" data-device=\"false\"  data-iconbg=\"#3A3A3A\" data-overcolor=\"\" data-defaultbg=\"#1f1f1e\" data-defaultplay=\"defaulticon\"><div class=\"ultv-video__play\" data-src=\"https:\/\/www.youtube.com\/embed\/F1Pn3d6nyX8?rel=0&#038;start&#038;end&#038;controls=1&#038;mute=0&#038;modestbranding=0&#038;autoplay=1\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ultv-video__thumb\" src=\"https:\/\/i.ytimg.com\/vi\/F1Pn3d6nyX8\/maxresdefault.jpg\"\/>\n\t\t\t\t\t\t\t\t<div class=\"ultv-video__play-icon  ultv-animation-none\" style=\"width:75px\"><svg height=\"100%\" version=\"1.1\" viewbox=\"0 0 68 48\" width=\"100%\"><path class=\"ultv-youtube-icon-bg\" d=\"m .66,37.62 c 0,0 .66,4.70 2.70,6.77 2.58,2.71 5.98,2.63 7.49,2.91 5.43,.52 23.10,.68 23.12,.68 .00,-1.3e-5 14.29,-0.02 23.81,-0.71 1.32,-0.15 4.22,-0.17 6.81,-2.89 2.03,-2.07 2.70,-6.77 2.70,-6.77 0,0 .67,-5.52 .67,-11.04 l 0,-5.17 c 0,-5.52 -0.67,-11.04 -0.67,-11.04 0,0 -0.66,-4.70 -2.70,-6.77 C 62.03,.86 59.13,.84 57.80,.69 48.28,0 34.00,0 34.00,0 33.97,0 19.69,0 10.18,.69 8.85,.84 5.95,.86 3.36,3.58 1.32,5.65 .66,10.35 .66,10.35 c 0,0 -0.55,4.50 -0.66,9.45 l 0,8.36 c .10,4.94 .66,9.45 .66,9.45 z\" fill=\"#1f1f1e\" ><\/path><path d=\"m 26.96,13.67 18.37,9.62 -18.37,9.55 -0.00,-19.17 z\" fill=\"#fff\"><\/path><path d=\"M 45.02,23.46 45.32,23.28 26.96,13.67 43.32,22.34 45.02,23.46 z\" fill=\"#ccc\"><\/path><\/svg><\/div> <\/div> <\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-size: 12pt; color: #000000;\"><strong>DT8987 Tavolo rotondo trasformabile con piani in ceramica\u00a0<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt; color: #000000;\"><strong>Materiale<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt;\">Top&amp;Estensione: <\/span>Pietra sinterizzata di 11 mm con venature simili al marmo<\/p>\n<p><span style=\"font-size: 10pt;\">Telaio&amp;gambe: metallo verniciato a polvere con finitura nera opaca<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Dimensione<\/strong><\/span> 1300(+500)*1300*760mm<\/p>\n<p><span style=\"color: #000000; font-size: 10pt;\"><strong>Pacchetto\u00a0<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt;\">1 set\/2 confezioni, 0,372CBM<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Richiedi un preventivo o un catalogo all'ingrosso<\/strong><br \/>\n<img decoding=\"async\" class=\"size-full wp-image-914 alignnone\" src=\"http:\/\/astonisa.com\/wp-content\/uploads\/2020\/10\/contact-us.gif\" alt=\"icona di contatto\" width=\"125\" height=\"70\" \/><br \/>\n<div class='fluentform ff-default fluentform_wrapper_4 ffs_default_wrap'><form data-form_id=\"4\" id=\"fluentform_4\" class=\"frm-fluent-form fluent_form_4 ff-el-form-top ff_form_instance_4_1 ff-form-loading ff_has_v3_recptcha ffs_default\" data-form_instance=\"ff_form_instance_4_1\" method=\"POST\" data-recptcha_key=\"6LdkO2MsAAAAAPSVddiMXJOpwbZ9Ot6nohKzaFdq\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Nuovo modulo di richiesta B2B (#4)<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='5582' \/><input type=\"hidden\" id=\"_fluentform_4_fluentformnonce\" name=\"_fluentform_4_fluentformnonce\" value=\"241312752c\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/dt_portfolio\/5582\" \/><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_4_input_text' id='label_ff_4_input_text' aria-label=\"Nome della societ\u00e0\">Nome della societ\u00e0<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Nome dell&#039;azienda o dell&#039;acquirente\" data-name=\"input_text\" id=\"ff_4_input_text\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_4_email' id='label_ff_4_email' aria-label=\"Email\">Email<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_4_email\" class=\"ff-el-form-control\" placeholder=\"E-mail aziendale\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group ff-el-form-hide_label'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_4_country-list' id='label_ff_4_country-list' aria-label=\"Paese\">Paese<\/label><\/div><div class='ff-el-input--content'><select name=\"country-list\" id=\"ff_4_country-list\" class=\"ff-el-form-control\" placeholder=\"Select Country\" data-name=\"country-list\" aria-invalid='false' aria-required=\"true\"><option value=''>Selezionare il Paese<\/option><option value='AF' >Afganistan<\/option><option value='AL' >Albania<\/option><option value='DZ' >Algeria<\/option><option value='AD' >Andorra<\/option><option value='AO' >Angola<\/option><option value='AI' >Anguilla<\/option><option value='AQ' >Antartide<\/option><option value='AG' >Antigua e Barbuda<\/option><option value='SA' >Arabia Saudita<\/option><option value='AR' >Argentina<\/option><option value='AM' >Armenia<\/option><option value='AW' >Aruba<\/option><option value='AU' >Australia<\/option><option value='AT' >Austria<\/option><option value='AZ' >Azerbaigian<\/option><option value='BS' >Bahamas<\/option><option value='BH' >Bahrein<\/option><option value='BD' >Bangladesh<\/option><option value='BB' >Barbados<\/option><option value='BE' >Belgio<\/option><option value='BZ' >Belize<\/option><option value='BJ' >Benin<\/option><option value='BM' >Bermuda<\/option><option value='BY' >Bielorussia<\/option><option value='MM' >Birmania<\/option><option value='BO' >Bolivia<\/option><option value='BQ' >Bonaire, Sant'Eustazio e Saba<\/option><option value='BA' >Bosnia ed Erzegovina<\/option><option value='BW' >Botswana<\/option><option value='BR' >Brasile<\/option><option value='BN' >Brunei<\/option><option value='BG' >Bulgaria<\/option><option value='BF' >Burkina Faso<\/option><option value='BI' >Burundi<\/option><option value='CV' >Cabo Verde<\/option><option value='KH' >Cambogia<\/option><option value='CM' >Camerun<\/option><option value='CA' >Canada<\/option><option value='TD' >Chad<\/option><option value='CL' >Cile<\/option><option value='CN' >Cina<\/option><option value='CY' >Cipro<\/option><option value='CO' >Colombia<\/option><option value='KM' >Comore<\/option><option value='KR' >Corea del Sud<\/option><option value='KP' >Corea del Nord<\/option><option value='CR' >Costa Rica<\/option><option value='CI' >Costa d'Avorio<\/option><option value='HR' >Croazia<\/option><option value='CU' >Cuba<\/option><option value='CW' >Cura\u00e7ao<\/option><option value='DK' >Danimarca<\/option><option value='EC' >Ecuador<\/option><option value='EG' >Egitto<\/option><option value='SV' >El Salvador<\/option><option value='AE' >Emirati Arabi Uniti<\/option><option value='ER' >Eritrea<\/option><option value='EE' >Estonia<\/option><option value='SZ' >Eswatini<\/option><option value='ET' >Etiopia<\/option><option value='FJ' >Figi<\/option><option value='PH' >Filippine<\/option><option value='FI' >Finlandia<\/option><option value='FR' >Francia<\/option><option value='GA' >Gabon<\/option><option value='GM' >Gambia<\/option><option value='GE' >Georgia<\/option><option value='GS' >Panino Georgia del Sud\/Isole<\/option><option value='DE' >Germania<\/option><option value='GH' >Ghana<\/option><option value='JM' >Giamaica<\/option><option value='JP' >Giappone<\/option><option value='GI' >Gibilterra<\/option><option value='DJ' >Gibuti<\/option><option value='JO' >Giordania<\/option><option value='GR' >Grecia<\/option><option value='GD' >Grenada<\/option><option value='GL' >Groenlandia<\/option><option value='GP' >Guadalupa<\/option><option value='GU' >Guam<\/option><option value='GT' >Guatemala<\/option><option value='GG' >Guernsey<\/option><option value='GN' >Guinea<\/option><option value='GW' >Guinea Bissau<\/option><option value='GQ' >Guinea Equatoriale<\/option><option value='GY' >Guyana<\/option><option value='GF' >Guyana francese<\/option><option value='HT' >Haiti<\/option><option value='HN' >Honduras<\/option><option value='HK' >Hong Kong<\/option><option value='BT' >Il Bhutan<\/option><option value='PY' >Il Paraguay<\/option><option value='IN' >India<\/option><option value='ID' >Indonesia<\/option><option value='IQ' >Iraq<\/option><option value='IE' >Irlanda<\/option><option value='IS' >Islanda<\/option><option value='BV' >Isola Bouvet<\/option><option value='NF' >Isola Norfolk<\/option><option value='IM' >Isola di Man<\/option><option value='CX' >Isola di Natale<\/option><option value='KY' >Isole Cayman<\/option><option value='CC' >Isole Cocos (Keeling)<\/option><option value='CK' >Isole Cook<\/option><option value='FK' >Isole Falkland<\/option><option value='FO' >Isole Faroe<\/option><option value='HM' >Isole Heard e McDonald<\/option><option value='MP' >Isole Marianne Settentrionali<\/option><option value='MH' >Isole Marshall<\/option><option value='SB' >Isole Salomone<\/option><option value='TC' >Isole Turks e Caicos<\/option><option value='VG' >Isole Vergini Britanniche<\/option><option value='VI' >Isole Vergini americane (USA)<\/option><option value='UM' >Isole minori esterne degli Stati Uniti (USA)<\/option><option value='AX' >Isole \u00c5land<\/option><option value='IL' >Israele<\/option><option value='IT' >Italia<\/option><option value='KZ' >Kazakistan<\/option><option value='KE' >Kenia<\/option><option value='KG' >Kirghizistan<\/option><option value='KI' >Kiribati<\/option><option value='XK' >Kosovo<\/option><option value='KW' >Kuwait<\/option><option value='IR' >L'Iran<\/option><option value='NA' >La Namibia<\/option><option value='DM' >La dominica<\/option><option value='LA' >Laos<\/option><option value='SC' >Le Seychelles<\/option><option value='LS' >Lesoto<\/option><option value='LV' >Lettonia<\/option><option value='LB' >Libano<\/option><option value='LR' >Liberia<\/option><option value='LY' >Libia<\/option><option value='LI' >Liechtenstein<\/option><option value='LT' >Lituania<\/option><option value='LU' >Lussemburgo<\/option><option value='MO' >Macao S.A.R., Cina<\/option><option value='MG' >Madagascar<\/option><option value='JE' >Maglia<\/option><option value='YT' >Majotte<\/option><option value='MW' >Malawi<\/option><option value='MY' >Malesia<\/option><option value='MV' >Maldive<\/option><option value='ML' >Mali<\/option><option value='MT' >Malta<\/option><option value='MA' >Marocco<\/option><option value='MQ' >Martinica<\/option><option value='MR' >Mauritania<\/option><option value='MU' >Maurizio<\/option><option value='MX' >Messico<\/option><option value='FM' >Micronesia<\/option><option value='MD' >Moldavia<\/option><option value='MC' >Monaco<\/option><option value='MN' >Mongolia<\/option><option value='ME' >Montenegro<\/option><option value='MS' >Montserrat<\/option><option value='MZ' >Mozambico<\/option><option value='NR' >Nauru<\/option><option value='NP' >Nepal<\/option><option value='NI' >Nicaragua<\/option><option value='NE' >Niger<\/option><option value='NG' >Nigeria<\/option><option value='NU' >Niue<\/option><option value='MK' >Macedonia del Nord<\/option><option value='NO' >Norvegia<\/option><option value='NC' >Nuova Caledonia<\/option><option value='NZ' >Nuova Zelanda<\/option><option value='OM' >Oman<\/option><option value='NL' >Paesi Bassi<\/option><option value='PK' >Pakistan<\/option><option value='PW' >Palau<\/option><option value='PA' >Panama<\/option><option value='PG' >Papua Nuova Guinea<\/option><option value='PE' >Per\u00f9<\/option><option value='PN' >Pitcairn<\/option><option value='PF' >Polinesia francese<\/option><option value='PL' >Polonia<\/option><option value='PT' >Portogallo<\/option><option value='PR' >Portorico<\/option><option value='QA' >Qatar<\/option><option value='GB' >Regno Unito (UK)<\/option><option value='CZ' >Repubblica Ceca<\/option><option value='CF' >Repubblica Centrafricana<\/option><option value='CD' >Repubblica Democratica del Congo (Kinshasa)<\/option><option value='DO' >Repubblica Dominicana<\/option><option value='CG' >Repubblica del Congo (Brazzaville)<\/option><option value='RO' >Romania<\/option><option value='RW' >Ruanda<\/option><option value='RU' >Russia<\/option><option value='RE' >Riunione<\/option><option value='EH' >Sahara Occidentale<\/option><option value='BL' >Saint Barth\u00e9lemy<\/option><option value='KN' >Saint Kitts e Nevis<\/option><option value='MF' >Saint Martin (parte francese)<\/option><option value='SX' >Saint Martin (parte olandese)<\/option><option value='PM' >Saint-Pierre e Miquelon<\/option><option value='VC' >Saint Vincent e Grenadine<\/option><option value='WS' >Samoa<\/option><option value='AS' >Samoa americane<\/option><option value='SM' >San Marino<\/option><option value='SH' >Sant'Elena<\/option><option value='LC' >Santa Lucia<\/option><option value='ST' >S\u00e3o Tom\u00e9 e Principe<\/option><option value='SN' >Senegal<\/option><option value='RS' >Serbia<\/option><option value='SL' >Sierra Leone<\/option><option value='SG' >Singapore<\/option><option value='SY' >Siria<\/option><option value='SK' >Slovacchia<\/option><option value='SI' >Slovenia<\/option><option value='SO' >Somalia<\/option><option value='ES' >Spagna<\/option><option value='LK' >Sri Lanka<\/option><option value='US' >Stati Uniti (USA)<\/option><option value='ZA' >Sudafrica<\/option><option value='SD' >Sudan<\/option><option value='SS' >Sudan del Sud<\/option><option value='SR' >Suriname<\/option><option value='SJ' >Svalbard e Jan Mayen<\/option><option value='SE' >Svezia<\/option><option value='CH' >Svizzera<\/option><option value='TJ' >Tagikistan<\/option><option value='TW' >Taiwan<\/option><option value='TZ' >Tanzania<\/option><option value='TF' >Territori francesi australi<\/option><option value='IO' >Territorio britannico dell'Oceano Indiano<\/option><option value='PS' >Territorio palestinese<\/option><option value='TH' >Thailandia<\/option><option value='TL' >Timor Est<\/option><option value='TG' >Togo<\/option><option value='TK' >Tokelau<\/option><option value='TO' >Tonga<\/option><option value='TT' >Trinidad e Tobago<\/option><option value='TN' >Tunisia<\/option><option value='TM' >Turkmenistan<\/option><option value='TV' >Tuvalu<\/option><option value='TR' >T\u00fcrkiye<\/option><option value='UA' >Ucraina<\/option><option value='UG' >Uganda<\/option><option value='HU' >Ungheria<\/option><option value='UY' >Uruguay<\/option><option value='UZ' >Uzbekistan<\/option><option value='VU' >Vanuatu<\/option><option value='VA' >Vaticano<\/option><option value='VE' >Venezuela<\/option><option value='VN' >Vietnam<\/option><option value='WF' >Wallis e Futuna<\/option><option value='YE' >Yemen<\/option><option value='ZM' >Zambia<\/option><option value='ZW' >Zimbabwe<\/option><\/select><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_4_description' id='label_ff_4_description' aria-label=\"Dettagli della ricerca\">Dettagli della ricerca<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"false\" aria-labelledby=\"label_ff_4_description\" name=\"description\" id=\"ff_4_description\" class=\"ff-el-form-control\" placeholder=\"Comunicateci il tipo di attivit\u00e0, il mercato di riferimento e i modelli a cui siete interessati.\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><input type=\"hidden\" name=\"Product_Name\" value=\"DT8987 Table\" data-name=\"Product_Name\" ><input type=\"hidden\" name=\"Page_URL\" value=\"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/dt_portfolio\/5582\" data-name=\"Page_URL\" ><div class='ff-el-group    ff-el-input--content'><div class='ff-el-form-check ff-el-tc'><label aria-label='Acconsento a che questo sito web memorizzi le informazioni da me inviate in modo da poter rispondere alla mia richiesta.' class='ff-el-form-check-label ff_tc_label' for=\"gdpr-agreement_f4a3874c060f1a85665e0f610d67f351\"><span class='ff_tc_checkbox'><input type=\"checkbox\" name=\"gdpr-agreement\" class=\"ff-el-form-check-input ff_gdpr_field\" data-name=\"gdpr-agreement\" id=\"gdpr-agreement_f4a3874c060f1a85665e0f610d67f351\"  value='on' aria-invalid='false' aria-required=\"true\"><\/span> <div class='ff_t_c'>Acconsento a che questo sito web memorizzi le informazioni da me inviate in modo da poter rispondere alla mia richiesta.<\/div><\/label><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Richiedi un preventivo all&#039;ingrosso\">Richiedi un preventivo all'ingrosso<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form><div id='fluentform_4_errors' class='ff-errors-in-stack ff_form_instance_4_1 ff-form-loading_errors ff_form_instance_4_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_4_1 = {\"id\":\"4\",\"ajaxUrl\":\"https:\\\/\\\/astonisa.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"asteriskPlacement\":\"asterisk-right\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_4_1\",\"form_id_selector\":\"fluentform_4\",\"rules\":{\"input_text\":{\"required\":{\"value\":true,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true},\"email\":{\"value\":true,\"message\":\"Questo campo deve contenere un indirizzo email valido\",\"global_message\":\"This field must contain a valid email\",\"global\":true}},\"country-list\":{\"required\":{\"value\":true,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"description\":{\"required\":{\"value\":false,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"gdpr-agreement\":{\"required\":{\"value\":true,\"message\":\"Questo campo \\u00e8 obbligatorio\",\"global_message\":\"This field is required\",\"global\":true}},\"g-recaptcha-response\":[]},\"debounce_time\":300};\n                            <\/script>\n            <\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Elevate la vostra linea di mobili da pranzo con il DT8987, un sofisticato tavolo da pranzo espandibile progettato per soddisfare le esigenze in evoluzione dei mercati globali. I distributori di mobili, gli importatori e i marchi che cercano soluzioni per tavoli da pranzo di fascia alta di forma rotonda o ovale, esteticamente piacevoli e funzionali, troveranno grandi idee in questo tavolo rotondo DT8987 Caratteristiche principali: Espandibile...<\/p>","protected":false},"author":1,"featured_media":5595,"comment_status":"open","ping_status":"closed","template":"","dt_portfolio_category":[35],"dt_portfolio_tags":[],"class_list":["post-5582","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-extendable-ceramic-dining-table","dt_portfolio_category-35","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DT8987 Table - Extendable ceramic &amp; glass dining table, dining chair China manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/astonisa.com\/it\/prodotto\/tavolo-trasformabile-da-rotondo-a-ovale-con-piani-in-ceramica-dt8987\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DT8987 Table - Extendable ceramic &amp; glass dining table, dining chair China manufacturer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astonisa.com\/it\/prodotto\/tavolo-trasformabile-da-rotondo-a-ovale-con-piani-in-ceramica-dt8987\/\" \/>\n<meta property=\"og:site_name\" content=\"Extendable ceramic &amp; glass dining table, dining chair China manufacturer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Astonisafurniture\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T03:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-Oval-Table.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/astonisa.com\\\/product\\\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\\\/\",\"url\":\"https:\\\/\\\/astonisa.com\\\/product\\\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\\\/\",\"name\":\"DT8987 Table - Extendable ceramic &amp; glass dining table, dining chair China manufacturer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astonisa.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astonisa.com\\\/product\\\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astonisa.com\\\/product\\\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astonisa.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DT8987-Oval-Table.webp\",\"datePublished\":\"2024-09-09T06:21:28+00:00\",\"dateModified\":\"2026-02-06T03:00:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astonisa.com\\\/product\\\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astonisa.com\\\/product\\\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/astonisa.com\\\/product\\\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astonisa.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DT8987-Oval-Table.webp\",\"contentUrl\":\"https:\\\/\\\/astonisa.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DT8987-Oval-Table.webp\",\"width\":600,\"height\":400,\"caption\":\"DT8987 Oval Table with ceramic top\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astonisa.com\\\/product\\\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/astonisa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041f\u043e\u0440\u0442\u0444\u043e\u043b\u0438\u043e\",\"item\":\"https:\\\/\\\/astonisa.com\\\/ru\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DT8987 Table\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astonisa.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/astonisa.com\\\/pl\\\/\",\"name\":\"Extendable ceramic &amp; glass dining table, dining chair China manufacturer\",\"description\":\"extendable dining table, dining chair\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astonisa.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DT8987 Tavolo - Tavolo da pranzo allungabile in ceramica e vetro, sedia da pranzo Produttore Cina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/astonisa.com\/it\/prodotto\/tavolo-trasformabile-da-rotondo-a-ovale-con-piani-in-ceramica-dt8987\/","og_locale":"it_IT","og_type":"article","og_title":"DT8987 Table - Extendable ceramic &amp; glass dining table, dining chair China manufacturer","og_url":"https:\/\/astonisa.com\/it\/prodotto\/tavolo-trasformabile-da-rotondo-a-ovale-con-piani-in-ceramica-dt8987\/","og_site_name":"Extendable ceramic &amp; glass dining table, dining chair China manufacturer","article_publisher":"https:\/\/www.facebook.com\/Astonisafurniture","article_modified_time":"2026-02-06T03:00:47+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-Oval-Table.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/astonisa.com\/product\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\/","url":"https:\/\/astonisa.com\/product\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\/","name":"DT8987 Tavolo - Tavolo da pranzo allungabile in ceramica e vetro, sedia da pranzo Produttore Cina","isPartOf":{"@id":"https:\/\/astonisa.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astonisa.com\/product\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\/#primaryimage"},"image":{"@id":"https:\/\/astonisa.com\/product\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\/#primaryimage"},"thumbnailUrl":"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-Oval-Table.webp","datePublished":"2024-09-09T06:21:28+00:00","dateModified":"2026-02-06T03:00:47+00:00","breadcrumb":{"@id":"https:\/\/astonisa.com\/product\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astonisa.com\/product\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/astonisa.com\/product\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\/#primaryimage","url":"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-Oval-Table.webp","contentUrl":"https:\/\/astonisa.com\/wp-content\/uploads\/2024\/09\/DT8987-Oval-Table.webp","width":600,"height":400,"caption":"DT8987 Oval Table with ceramic top"},{"@type":"BreadcrumbList","@id":"https:\/\/astonisa.com\/product\/transformable-table-from-round-to-oval-with-ceramic-tops-dt8987\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/astonisa.com\/"},{"@type":"ListItem","position":2,"name":"\u041f\u043e\u0440\u0442\u0444\u043e\u043b\u0438\u043e","item":"https:\/\/astonisa.com\/ru\/product\/"},{"@type":"ListItem","position":3,"name":"DT8987 Table"}]},{"@type":"WebSite","@id":"https:\/\/astonisa.com\/pl\/#website","url":"https:\/\/astonisa.com\/pl\/","name":"Tavolo da pranzo allungabile in ceramica e vetro, sedia da pranzo Produttore Cina","description":"tavolo da pranzo allungabile, sedia da pranzo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astonisa.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/dt_portfolio\/5582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/comments?post=5582"}],"version-history":[{"count":3,"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/dt_portfolio\/5582\/revisions"}],"predecessor-version":[{"id":6868,"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/dt_portfolio\/5582\/revisions\/6868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/media\/5595"}],"wp:attachment":[{"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/media?parent=5582"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/dt_portfolio_category?post=5582"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/astonisa.com\/it\/wp-json\/wp\/v2\/dt_portfolio_tags?post=5582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}